{"id":3193855,"date":"2025-09-01T05:53:07","date_gmt":"2025-09-01T05:53:07","guid":{"rendered":"https:\/\/jomare.pt\/produto\/telefac-dpf252we-frigorifico\/"},"modified":"2026-07-15T05:55:11","modified_gmt":"2026-07-15T05:55:11","slug":"telefac-dpf252we-frigorifico","status":"publish","type":"product","link":"https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/","title":{"rendered":"TELEFAC DPF252WE FRIGORIFICO"},"content":{"rendered":"<p>Produto: Telefac DPF252WE <br \/>Tipo: Frigor\u00edfico 2 portas <br \/>Instala\u00e7\u00e3o: Livre <br \/>Cor: Branco <br \/>Refrigera\u00e7\u00e3o: Est\u00e1tico Less Frost <br \/>Classe energ\u00e9tica: E <br \/>Consumo: 176 kWh\/ano <br \/>N\u00edvel ru\u00eddo: 40 dB <br \/>Capac. total: 204 L <br \/>Capac. frigo: 163 L <br \/>Capac. cong.: 41 L <br \/>Prateleiras: Vidro regul\u00e1veis <br \/>Portas: Revers\u00edveis <br \/>Descongela\u00e7\u00e3o: Auto (frio) <br \/>Dimens\u00f5es (A\u00d7L\u00d7P): 143\u00d755\u00d755 cm <br \/>Capacidade pessoas: 3-4 <br \/>Clima: N, ST (16-38 \u00b0C) <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Produto: Telefac DPF252WE  Tipo: Frigor\u00edfico 2 portas  Instala\u00e7\u00e3o: Livre  Cor: Branco  Refrigera\u00e7\u00e3o: Est\u00e1tico Less Frost  Classe energ\u00e9tica: E  Consumo: 176 kWh\/ano  N\u00edvel ru\u00eddo: 40 dB  Capac. total: 204 L  Capac. frigo: 163 L  Capac. cong.: 41 L  Prateleiras: Vidro regul\u00e1veis  Portas: Revers\u00edveis  Descongela\u00e7\u00e3o: Auto (frio)  Dimens\u00f5es (A\u00d7L\u00d7P): 143\u00d755\u00d755 cm  Capacidade pessoas: 3-4  Clima: N, ST (16-38 \u00b0C)  <\/p>\n","protected":false},"featured_media":3339574,"comment_status":"open","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[368,371,369],"product_tag":[],"class_list":["post-3193855","product","type-product","status-publish","has-post-thumbnail","product_cat-electrodomesticos","product_cat-frigorificos","product_cat-grandes-domesticos","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TELEFAC DPF252WE FRIGORIFICO - Jomare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TELEFAC DPF252WE FRIGORIFICO - Jomare\" \/>\n<meta property=\"og:description\" content=\"Produto: Telefac DPF252WE Tipo: Frigor\u00edfico 2 portas Instala\u00e7\u00e3o: Livre Cor: Branco Refrigera\u00e7\u00e3o: Est\u00e1tico Less Frost Classe energ\u00e9tica: E Consumo: 176 kWh\/ano N\u00edvel ru\u00eddo: 40 dB Capac. total: 204 L Capac. frigo: 163 L Capac. cong.: 41 L Prateleiras: Vidro regul\u00e1veis Portas: Revers\u00edveis Descongela\u00e7\u00e3o: Auto (frio) Dimens\u00f5es (A\u00d7L\u00d7P): 143\u00d755\u00d755 cm Capacidade pessoas: 3-4 Clima: N, ST (16-38 \u00b0C)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/\" \/>\n<meta property=\"og:site_name\" content=\"Jomare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T05:55:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jomare.pt\/wp-content\/uploads\/produtos\/27921.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/telefac-dpf252we-frigorifico\\\/\",\"url\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/telefac-dpf252we-frigorifico\\\/\",\"name\":\"TELEFAC DPF252WE FRIGORIFICO - Jomare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/telefac-dpf252we-frigorifico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/telefac-dpf252we-frigorifico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jomare.pt\\\/wp-content\\\/uploads\\\/produtos\\\/27921.png\",\"datePublished\":\"2025-09-01T05:53:07+00:00\",\"dateModified\":\"2026-07-15T05:55:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/telefac-dpf252we-frigorifico\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/telefac-dpf252we-frigorifico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/telefac-dpf252we-frigorifico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jomare.pt\\\/wp-content\\\/uploads\\\/produtos\\\/27921.png\",\"contentUrl\":\"https:\\\/\\\/jomare.pt\\\/wp-content\\\/uploads\\\/produtos\\\/27921.png\",\"width\":553,\"height\":582},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/telefac-dpf252we-frigorifico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jomare.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/jomare.pt\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TELEFAC DPF252WE FRIGORIFICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/jomare.pt\\\/en\\\/\",\"name\":\"Jomare\",\"description\":\"Novas Ideias | Novas Solu\u00e7\u00f5es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jomare.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TELEFAC DPF252WE FRIGORIFICO - Jomare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/","og_locale":"en_US","og_type":"article","og_title":"TELEFAC DPF252WE FRIGORIFICO - Jomare","og_description":"Produto: Telefac DPF252WE Tipo: Frigor\u00edfico 2 portas Instala\u00e7\u00e3o: Livre Cor: Branco Refrigera\u00e7\u00e3o: Est\u00e1tico Less Frost Classe energ\u00e9tica: E Consumo: 176 kWh\/ano N\u00edvel ru\u00eddo: 40 dB Capac. total: 204 L Capac. frigo: 163 L Capac. cong.: 41 L Prateleiras: Vidro regul\u00e1veis Portas: Revers\u00edveis Descongela\u00e7\u00e3o: Auto (frio) Dimens\u00f5es (A\u00d7L\u00d7P): 143\u00d755\u00d755 cm Capacidade pessoas: 3-4 Clima: N, ST (16-38 \u00b0C)","og_url":"https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/","og_site_name":"Jomare","article_modified_time":"2026-07-15T05:55:11+00:00","og_image":[{"width":553,"height":582,"url":"https:\/\/jomare.pt\/wp-content\/uploads\/produtos\/27921.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/","url":"https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/","name":"TELEFAC DPF252WE FRIGORIFICO - Jomare","isPartOf":{"@id":"https:\/\/jomare.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/#primaryimage"},"image":{"@id":"https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/#primaryimage"},"thumbnailUrl":"https:\/\/jomare.pt\/wp-content\/uploads\/produtos\/27921.png","datePublished":"2025-09-01T05:53:07+00:00","dateModified":"2026-07-15T05:55:11+00:00","breadcrumb":{"@id":"https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/#primaryimage","url":"https:\/\/jomare.pt\/wp-content\/uploads\/produtos\/27921.png","contentUrl":"https:\/\/jomare.pt\/wp-content\/uploads\/produtos\/27921.png","width":553,"height":582},{"@type":"BreadcrumbList","@id":"https:\/\/jomare.pt\/en\/produto\/telefac-dpf252we-frigorifico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jomare.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/jomare.pt\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"TELEFAC DPF252WE FRIGORIFICO"}]},{"@type":"WebSite","@id":"https:\/\/jomare.pt\/en\/#website","url":"https:\/\/jomare.pt\/en\/","name":"Jomare","description":"Novas Ideias | Novas Solu\u00e7\u00f5es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jomare.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/product\/3193855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/comments?post=3193855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/media\/3339574"}],"wp:attachment":[{"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/media?parent=3193855"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/product_brand?post=3193855"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/product_cat?post=3193855"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/product_tag?post=3193855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}