{"id":3193665,"date":"2024-06-02T06:13:32","date_gmt":"2024-06-02T06:13:32","guid":{"rendered":"https:\/\/jomare.pt\/produto\/hoover-hmc510uv011-aspirador-colcho\/"},"modified":"2026-07-14T06:28:16","modified_gmt":"2026-07-14T06:28:16","slug":"hoover-hmc510uv011-aspirador-colcho","status":"publish","type":"product","link":"https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/","title":{"rendered":"HOOVER HMC510UV011 ASPIRADOR COLCHO"},"content":{"rendered":"<p>HOOVER HMC510UV 011 <br \/>ASPIRADOR COLCH\u00d5ES <br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211; <br \/>CARACTER\u00cdSTICAS: <br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211; <br \/>Marca: Hoover <br \/>Modelo: HMC510UV 011 <br \/>Gama: Ultra Vortex II <br \/>Tipo: Aspirador de M\u00e3o <br \/>Uso: Colch\u00f5es e Sof\u00e1s <br \/>Pot\u00eancia: 500W <br \/>L\u00e2mpada UV-C: Sim <br \/>Fun\u00e7\u00e3o Calor: Sim (50\u00b0C) <br \/>Tecnologia: Cicl\u00f3nica <br \/>Capacidade: 0.3 Litros <br \/>Comprimento Cabo: 5m <br \/>Modos: 3 Fun\u00e7\u00f5es <br \/>Escova Rotativa: Sim <br \/>Sensor P\u00f3: Inteligente <br \/>Filtro: EPA Lav\u00e1vel <br \/>Ideal para: Alergias <br \/>Peso: 2.15 kg <br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211; <br \/>DIMENS\u00d5ES: <br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211; <br \/>Altura: 21.4 cm <br \/>Largura: 28.2 cm <br \/>Profundidade: 33.9 cm <br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211; <br \/>EFICI\u00caNCIA: <br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211; <br \/>Classe Energ\u00e9tica: N\/A* <br \/>*Pequeno Dom\u00e9stico <br \/>Efic\u00e1cia UV: 99.9% <br \/>Elimina \u00c1caros: Sim <br \/>Esteriliza\u00e7\u00e3o: Sim <br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211; <br \/>      KEYWORDS: <br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211; <br \/>Hoover HMC510UV <br \/>Aspirador colch\u00f5es <br \/>Hoover Ultra Vortex <br \/>Eliminar \u00e1caros <br \/>Aspirador anti-al\u00e9rgico <br \/>L\u00e2mpada UV-C colch\u00f5es <br \/>Limpeza de estofos <br \/>Hoover 500W <br \/>Aspirador sof\u00e1s <br \/>Higiene da cama <br \/>Hoover Portugal <\/p>\n","protected":false},"excerpt":{"rendered":"<p>HOOVER HMC510UV 011  ASPIRADOR COLCH\u00d5ES  &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;  CARACTER\u00cdSTICAS:  &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;  Marca: Hoover  Modelo: HMC510UV 011  Gama: Ultra Vortex II  Tipo: Aspirador de M\u00e3o  Uso: Colch\u00f5es e Sof\u00e1s  Pot\u00eancia: 500W  L\u00e2mpada UV-C: Sim  Fun\u00e7\u00e3o Calor: Sim (50\u00b0C)  Tecnologia: Cicl\u00f3nica  Capacidade: 0.3 Litros  Comprimento Cabo: 5m  Modos: 3 Fun\u00e7\u00f5es  Escova Rotativa: Sim  Sensor P\u00f3: Inteligente  Filtro: EPA Lav\u00e1vel  Ideal para: Alergias  Peso: 2.15 kg  &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;  DIMENS\u00d5ES:  &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;  Altura: 21.4 cm  Largura: 28.2 cm  Profundidade: 33.9 cm  &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;  EFICI\u00caNCIA:  &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;  Classe Energ\u00e9tica: N\/A*  *Pequeno Dom\u00e9stico  Efic\u00e1cia UV: 99.9%  Elimina \u00c1caros: Sim  Esteriliza\u00e7\u00e3o: Sim  &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;        KEYWORDS:  &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;  Hoover HMC510UV  Aspirador colch\u00f5es  Hoover Ultra Vortex  Eliminar \u00e1caros  Aspirador anti-al\u00e9rgico  L\u00e2mpada UV-C colch\u00f5es  Limpeza de estofos  Hoover 500W  Aspirador sof\u00e1s  Higiene da cama  Hoover Portugal  <\/p>\n","protected":false},"featured_media":3338847,"comment_status":"open","ping_status":"open","template":"","meta":[],"product_brand":[567],"product_cat":[381,380,368],"product_tag":[],"class_list":["post-3193665","product","type-product","status-publish","has-post-thumbnail","product_brand-hoover","product_cat-aspiradores-cuidados-do-lar","product_cat-cuidados-do-lar","product_cat-electrodomesticos","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HOOVER HMC510UV011 ASPIRADOR COLCHO - Jomare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HOOVER HMC510UV011 ASPIRADOR COLCHO - Jomare\" \/>\n<meta property=\"og:description\" content=\"HOOVER HMC510UV 011 ASPIRADOR COLCH\u00d5ES -------------------------- CARACTER\u00cdSTICAS: -------------------------- Marca: Hoover Modelo: HMC510UV 011 Gama: Ultra Vortex II Tipo: Aspirador de M\u00e3o Uso: Colch\u00f5es e Sof\u00e1s Pot\u00eancia: 500W L\u00e2mpada UV-C: Sim Fun\u00e7\u00e3o Calor: Sim (50\u00b0C) Tecnologia: Cicl\u00f3nica Capacidade: 0.3 Litros Comprimento Cabo: 5m Modos: 3 Fun\u00e7\u00f5es Escova Rotativa: Sim Sensor P\u00f3: Inteligente Filtro: EPA Lav\u00e1vel Ideal para: Alergias Peso: 2.15 kg -------------------------- DIMENS\u00d5ES: -------------------------- Altura: 21.4 cm Largura: 28.2 cm Profundidade: 33.9 cm -------------------------- EFICI\u00caNCIA: -------------------------- Classe Energ\u00e9tica: N\/A* *Pequeno Dom\u00e9stico Efic\u00e1cia UV: 99.9% Elimina \u00c1caros: Sim Esteriliza\u00e7\u00e3o: Sim --------------------------    KEYWORDS: -------------------------- Hoover HMC510UV Aspirador colch\u00f5es Hoover Ultra Vortex Eliminar \u00e1caros Aspirador anti-al\u00e9rgico L\u00e2mpada UV-C colch\u00f5es Limpeza de estofos Hoover 500W Aspirador sof\u00e1s Higiene da cama Hoover Portugal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/\" \/>\n<meta property=\"og:site_name\" content=\"Jomare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T06:28:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jomare.pt\/wp-content\/uploads\/produtos\/27011.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/hoover-hmc510uv011-aspirador-colcho\\\/\",\"url\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/hoover-hmc510uv011-aspirador-colcho\\\/\",\"name\":\"HOOVER HMC510UV011 ASPIRADOR COLCHO - Jomare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/hoover-hmc510uv011-aspirador-colcho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/hoover-hmc510uv011-aspirador-colcho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jomare.pt\\\/wp-content\\\/uploads\\\/produtos\\\/27011.png\",\"datePublished\":\"2024-06-02T06:13:32+00:00\",\"dateModified\":\"2026-07-14T06:28:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/hoover-hmc510uv011-aspirador-colcho\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/hoover-hmc510uv011-aspirador-colcho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/hoover-hmc510uv011-aspirador-colcho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jomare.pt\\\/wp-content\\\/uploads\\\/produtos\\\/27011.png\",\"contentUrl\":\"https:\\\/\\\/jomare.pt\\\/wp-content\\\/uploads\\\/produtos\\\/27011.png\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/produto\\\/hoover-hmc510uv011-aspirador-colcho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jomare.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/jomare.pt\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HOOVER HMC510UV011 ASPIRADOR COLCHO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jomare.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/jomare.pt\\\/en\\\/\",\"name\":\"Jomare\",\"description\":\"Novas Ideias | Novas Solu\u00e7\u00f5es\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jomare.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HOOVER HMC510UV011 ASPIRADOR COLCHO - Jomare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/","og_locale":"en_US","og_type":"article","og_title":"HOOVER HMC510UV011 ASPIRADOR COLCHO - Jomare","og_description":"HOOVER HMC510UV 011 ASPIRADOR COLCH\u00d5ES -------------------------- CARACTER\u00cdSTICAS: -------------------------- Marca: Hoover Modelo: HMC510UV 011 Gama: Ultra Vortex II Tipo: Aspirador de M\u00e3o Uso: Colch\u00f5es e Sof\u00e1s Pot\u00eancia: 500W L\u00e2mpada UV-C: Sim Fun\u00e7\u00e3o Calor: Sim (50\u00b0C) Tecnologia: Cicl\u00f3nica Capacidade: 0.3 Litros Comprimento Cabo: 5m Modos: 3 Fun\u00e7\u00f5es Escova Rotativa: Sim Sensor P\u00f3: Inteligente Filtro: EPA Lav\u00e1vel Ideal para: Alergias Peso: 2.15 kg -------------------------- DIMENS\u00d5ES: -------------------------- Altura: 21.4 cm Largura: 28.2 cm Profundidade: 33.9 cm -------------------------- EFICI\u00caNCIA: -------------------------- Classe Energ\u00e9tica: N\/A* *Pequeno Dom\u00e9stico Efic\u00e1cia UV: 99.9% Elimina \u00c1caros: Sim Esteriliza\u00e7\u00e3o: Sim --------------------------    KEYWORDS: -------------------------- Hoover HMC510UV Aspirador colch\u00f5es Hoover Ultra Vortex Eliminar \u00e1caros Aspirador anti-al\u00e9rgico L\u00e2mpada UV-C colch\u00f5es Limpeza de estofos Hoover 500W Aspirador sof\u00e1s Higiene da cama Hoover Portugal","og_url":"https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/","og_site_name":"Jomare","article_modified_time":"2026-07-14T06:28:16+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/jomare.pt\/wp-content\/uploads\/produtos\/27011.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/","url":"https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/","name":"HOOVER HMC510UV011 ASPIRADOR COLCHO - Jomare","isPartOf":{"@id":"https:\/\/jomare.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/#primaryimage"},"image":{"@id":"https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/#primaryimage"},"thumbnailUrl":"https:\/\/jomare.pt\/wp-content\/uploads\/produtos\/27011.png","datePublished":"2024-06-02T06:13:32+00:00","dateModified":"2026-07-14T06:28:16+00:00","breadcrumb":{"@id":"https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/#primaryimage","url":"https:\/\/jomare.pt\/wp-content\/uploads\/produtos\/27011.png","contentUrl":"https:\/\/jomare.pt\/wp-content\/uploads\/produtos\/27011.png","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/jomare.pt\/en\/produto\/hoover-hmc510uv011-aspirador-colcho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jomare.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/jomare.pt\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"HOOVER HMC510UV011 ASPIRADOR COLCHO"}]},{"@type":"WebSite","@id":"https:\/\/jomare.pt\/en\/#website","url":"https:\/\/jomare.pt\/en\/","name":"Jomare","description":"Novas Ideias | Novas Solu\u00e7\u00f5es","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jomare.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/product\/3193665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/comments?post=3193665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/media\/3338847"}],"wp:attachment":[{"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/media?parent=3193665"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/product_brand?post=3193665"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/product_cat?post=3193665"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jomare.pt\/en\/wp-json\/wp\/v2\/product_tag?post=3193665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}